{"id":3322,"date":"2022-09-05T14:04:51","date_gmt":"2022-09-05T12:04:51","guid":{"rendered":"https:\/\/www.assip.org\/pour-les-patientes\/temoignages\/"},"modified":"2026-06-08T13:43:41","modified_gmt":"2026-06-08T11:43:41","slug":"temoignages","status":"publish","type":"page","link":"https:\/\/www.assip.org\/fr\/pour-les-patientes\/temoignages\/","title":{"rendered":"Qu&rsquo;en disent les autres?"},"content":{"rendered":"\n<h1 class=\"wp-block-heading\"><strong>Qu&rsquo;en disent les autres?<\/strong><\/h1>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div id=\"wp-block-themeisle-blocks-advanced-columns-0c978e58\" class=\"wp-block-themeisle-blocks-advanced-columns has-1-columns has-desktop-equal-layout has-tablet-equal-layout has-mobile-equal-layout has-vertical-unset\"><div class=\"wp-block-themeisle-blocks-advanced-columns-overlay\"><\/div><div class=\"innerblocks-wrap\">\n<div id=\"wp-block-themeisle-blocks-advanced-column-e35320b2\" class=\"wp-block-themeisle-blocks-advanced-column\">\n<h1 class=\"wp-block-heading\">T\u00e9moignages<\/h1>\n<\/div>\n<\/div><\/div>\n\n\n\n<div id=\"wp-block-themeisle-blocks-advanced-columns-dc6cdc07\" class=\"wp-block-themeisle-blocks-advanced-columns alignfull has-1-columns has-desktop-equal-layout has-tablet-equal-layout has-mobile-equal-layout has-vertical-unset has-light-bg\"><div class=\"wp-block-themeisle-blocks-advanced-columns-overlay\"><\/div><div class=\"innerblocks-wrap\">\n<div id=\"wp-block-themeisle-blocks-advanced-column-fd1590f8\" class=\"wp-block-themeisle-blocks-advanced-column\">\n<figure class=\"wp-block-pullquote has-nv-dark-bg-color has-nv-light-bg-background-color has-text-color has-background has-small-font-size\"><blockquote><p>L\u2019accompagnement ASSIP m\u2019a beaucoup aid\u00e9 \u00e0 mieux me comprendre et \u00e0 prendre soin de ma sant\u00e9 psychique. Les lettres que je re\u00e7ois r\u00e9guli\u00e8rement me rappellent l\u2019importance de rester attentive \u00e0 moi-m\u00eame. Pendant le programme, je me suis sentie v\u00e9ritablement \u00e9cout\u00e9e et comprise : tous les aspects de ma situation ont \u00e9t\u00e9 pris en compte, pas seulement les plus \u00e9vidents. Je suis tr\u00e8s reconnaissante pour ce soutien.<\/p><cite>Madame P., ancienne patiente de l&rsquo;ASSIP<\/cite><\/blockquote><\/figure>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-pullquote has-nv-dark-bg-color has-nv-light-bg-background-color has-text-color has-background has-small-font-size\"><blockquote><p>ASSIP m\u2019a apport\u00e9 un sentiment de s\u00e9curit\u00e9 et le fait de mieux comprendre mes pens\u00e9es suicidaires m\u2019a fait beaucoup de bien. Je tiens \u00e0 vous en remercier sinc\u00e8rement.<\/p><cite>Monsieur C., ancien patient de l&rsquo;ASSIP<\/cite><\/blockquote><\/figure>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-pullquote has-nv-dark-bg-color has-nv-light-bg-background-color has-text-color has-background has-small-font-size\"><blockquote><p>Le programme ASSIP m&rsquo;a beaucoup aid\u00e9. J&rsquo;ai pu terminer ma psychoth\u00e9rapie avec succ\u00e8s et arr\u00eater mes m\u00e9dicaments. Depuis, je me sens toujours stable et j&rsquo;ai pu surmonter seul des situations difficiles. Au cours des derniers mois, j&rsquo;ai v\u00e9cu beaucoup d&rsquo;autoefficacit\u00e9 et je n&rsquo;ai pas rencontr\u00e9 de crises majeures. Je suis confiante que je serai \u00e9galement capable de bien g\u00e9rer les situations difficiles \u00e0 l&rsquo;avenir, car j&rsquo;ai acquis des comp\u00e9tences pr\u00e9cieuses sur lesquelles je peux toujours compter.<\/p><cite>Madame B., ancienne patiente de l&rsquo;ASSIP<\/cite><\/blockquote><\/figure>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-pullquote has-nv-dark-bg-color has-nv-light-bg-background-color has-text-color has-background has-small-font-size\"><blockquote><p>Je tiens \u00e0 vous remercier \u00e0 nouveau pour l&rsquo;accompagnement dans le cadre de l&rsquo;ASSIP. Les s\u00e9ances avec vous ont \u00e9t\u00e9 une exp\u00e9rience limite importante, au cours de laquelle je me suis senti tr\u00e8s bien accompagn\u00e9. Avec du recul, c&rsquo;est uniquement gr\u00e2ce \u00e0 l&rsquo;ASSIP que j&rsquo;ai pu accepter et int\u00e9grer, et que j&rsquo;ai d\u00fb int\u00e9grer, \u00e0 quel point j&rsquo;en \u00e9tais arriv\u00e9.<\/p><cite>Madame G., ancienne patiente de l&rsquo;ASSIP<\/cite><\/blockquote><\/figure>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-pullquote has-nv-dark-bg-color has-nv-light-bg-background-color has-text-color has-background has-small-font-size\"><blockquote><p>Beaucoup de choses ont chang\u00e9 entre-temps\u2026 M\u00eame dans cette p\u00e9riode tr\u00e8s difficile, je n&rsquo;ai jamais pens\u00e9 au suicide, gr\u00e2ce \u00e0 vous et \u00e0 votre th\u00e9rapie. Aujourd&rsquo;hui, je vis selon la devise: &lsquo;Abandonner n&rsquo;est pas une option, il y a des probl\u00e8mes, mais encore plus de solutions.&rsquo; Un grand, grand merci!<\/p><cite>Monsieur B., ancien patient de l&rsquo;ASSIP<\/cite><\/blockquote><\/figure>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-pullquote has-nv-dark-bg-color has-nv-light-bg-background-color has-text-color has-background has-small-font-size\"><blockquote><p>ASSIP m&rsquo;a aid\u00e9 \u00e0 retrouver davantage de s\u00e9curit\u00e9 et \u00e0 me sentir moins expos\u00e9e \u00e0 ces \u00e9tats tr\u00e8s mena\u00e7ants. Je suis \u00e9galement tr\u00e8s reconnaissante de pouvoir me tourner \u00e0 nouveau vers vous \u00e0 l&rsquo;avenir, si jamais je venais \u00e0 atteindre mes limites.<\/p><cite>Madame M., ancienne patiente de l&rsquo;ASSIP<\/cite><\/blockquote><\/figure>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-pullquote has-nv-dark-bg-color has-nv-light-bg-background-color has-text-color has-background has-small-font-size\"><blockquote><p>Je pense tr\u00e8s fort \u00e0 cette p\u00e9riode en ce moment, \u00e0 ce moment, \u00e0 cette tentative, \u00e0 ce sentiment \u00e9trange ce jour-l\u00e0, \u00e0 la peur de ne plus jamais revoir ma famille, au r\u00e9veil \u00e0 l&rsquo;h\u00f4pital, \u00e0 cette deuxi\u00e8me chance, aux yeux de ma femme qui m&rsquo;ont regard\u00e9, au moment o\u00f9 j&rsquo;ai pu prendre mes enfants dans mes bras, aux s\u00e9ances bouleversantes avec vous&#8230; Vous m&rsquo;avez apport\u00e9 un soutien et une confiance infinis. Pour cela, je veux vous remercier. Pour toujours.<\/p><cite>Nicolas D., ancien patient de l&rsquo;ASSIP<\/cite><\/blockquote><\/figure>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-pullquote has-nv-dark-bg-color has-nv-light-bg-background-color has-text-color has-background has-small-font-size\"><blockquote><p>Je vous remercie beaucoup pour votre pr\u00e9cieux travail ASSIP, rapports compris. Deux de mes patientes ont d\u00e9j\u00e0 appr\u00e9ci\u00e9 ces entretiens personnels cibl\u00e9s &#8211; d&rsquo;abord difficiles, mais ensuite tr\u00e8s constructifs. Et pour moi, en tant que psychiatre en cabinet, c&rsquo;est bien s\u00fbr utile et soulageant.<\/p><cite>Dr. med. R.B.D, sp\u00e9cialiste en psychiatrie et psychoth\u00e9rapie<\/cite><\/blockquote><\/figure>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-pullquote has-nv-dark-bg-color has-nv-light-bg-background-color has-text-color has-background has-small-font-size\"><blockquote><p>Les s\u00e9ances de th\u00e9rapie avec vous m&rsquo;ont beaucoup aid\u00e9, j&rsquo;ai toujours le leporello dans mon porte-monnaie. Je sais comment mieux g\u00e9rer les pens\u00e9es de la mort. Je reconnais mieux les signaux d&rsquo;alarme et je peux r\u00e9agir.<\/p><cite>Johann P., ancien patient de l&rsquo;ASSIP<\/cite><\/blockquote><\/figure>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-pullquote has-nv-dark-bg-color has-nv-light-bg-background-color has-text-color has-background has-small-font-size\"><blockquote><p>La consultation ASSIP m&rsquo;a beaucoup aid\u00e9 \u00e0 l&rsquo;\u00e9poque \u00e0 surmonter mes crises suicidaires et \u00e0 aller de l&rsquo;avant. J&rsquo;appr\u00e9cie beaucoup les lettres que je re\u00e7ois encore r\u00e9guli\u00e8rement et je vous remercie, vous m&rsquo;avez beaucoup aid\u00e9.<\/p><cite>Ancien patient de l&rsquo;ASSIP<\/cite><\/blockquote><\/figure>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-pullquote has-nv-dark-bg-color has-nv-light-bg-background-color has-text-color has-background has-small-font-size\"><blockquote><p>J&rsquo;ai appris \u00e0 chercher le dialogue avec mon entourage lorsque je ne me sens pas bien. Avant, je le faisais rarement. Je vous suis toujours reconnaissant pour votre aide et j&rsquo;ai enregistr\u00e9 tout ce que j&rsquo;ai appris avec vous. Vous avez jou\u00e9 un r\u00f4le d\u00e9cisif pour moi et pour mon parcours. Je sais maintenant comment mieux g\u00e9rer les mauvaises pens\u00e9es, je reconnais mieux les signaux d&rsquo;alarme et je peux r\u00e9agir.<\/p><cite>Ancien patient de l&rsquo;ASSIP<\/cite><\/blockquote><\/figure>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-pullquote has-nv-dark-bg-color has-nv-light-bg-background-color has-text-color has-background has-small-font-size\"><blockquote><p>Les lettres font souvent remonter de nombreux souvenirs dont je pr\u00e9f\u00e9rerais ne pas me souvenir. Et pourtant, je trouve qu&rsquo;il est important de les recevoir. Elles m&rsquo;aident \u00e0 r\u00e9fl\u00e9chir \u00e0 ce que je peux faire quand je ne me sens pas bien. Ce n&rsquo;est alors pas toujours tr\u00e8s agr\u00e9able, mais toujours important. Merci pour votre aide. Vous faites un travail incroyablement pr\u00e9cieux.<\/p><cite>Ancienne patiente de l&rsquo;ASSIP<\/cite><\/blockquote><\/figure>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-pullquote has-nv-dark-bg-color has-nv-light-bg-background-color has-text-color has-background has-small-font-size\"><blockquote><p>Le programme ASSIP m&rsquo;a beaucoup aid\u00e9 \u00e0 sortir de ma crise, notamment gr\u00e2ce \u00e0 l&rsquo;enregistrement vid\u00e9o qui m&rsquo;a permis de prendre une certaine distance par rapport au pass\u00e9. Je n&rsquo;aurais jamais pens\u00e9 \u00e0 l&rsquo;\u00e9poque qu&rsquo;un programme aussi compact aurait un tel impact. J&rsquo;ai beaucoup appris sur moi-m\u00eame au cours des deux derni\u00e8res ann\u00e9es et je peux d\u00e9sormais g\u00e9rer les situations difficiles diff\u00e9remment. Merci beaucoup pour votre grand soutien empathique.<\/p><cite>Ancienne patiente de l&rsquo;ASSIP<\/cite><\/blockquote><\/figure>\n<\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Qu&rsquo;en disent les autres?<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":3316,"menu_order":6,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"off","neve_meta_content_width":100,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"class_list":["post-3322","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Qu&#039;en disent les autres? | ASSIP flex<\/title>\n<meta name=\"description\" content=\"Dans les t\u00e9moignages, vous trouverez les r\u00e9actions des patient(e)s et des th\u00e9rapeutes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.assip.org\/fr\/pour-les-patientes\/temoignages\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Qu&#039;en disent les autres? | ASSIP flex\" \/>\n<meta property=\"og:description\" content=\"Dans les t\u00e9moignages, vous trouverez les r\u00e9actions des patient(e)s et des th\u00e9rapeutes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.assip.org\/fr\/pour-les-patientes\/temoignages\/\" \/>\n<meta property=\"og:site_name\" content=\"ASSIP flex\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-08T11:43:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.assip.org\\\/fr\\\/pour-les-patientes\\\/temoignages\\\/\",\"url\":\"https:\\\/\\\/www.assip.org\\\/fr\\\/pour-les-patientes\\\/temoignages\\\/\",\"name\":\"Qu'en disent les autres? | ASSIP flex\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.assip.org\\\/fr\\\/#website\"},\"datePublished\":\"2022-09-05T12:04:51+00:00\",\"dateModified\":\"2026-06-08T11:43:41+00:00\",\"description\":\"Dans les t\u00e9moignages, vous trouverez les r\u00e9actions des patient(e)s et des th\u00e9rapeutes.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.assip.org\\\/fr\\\/pour-les-patientes\\\/temoignages\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.assip.org\\\/fr\\\/pour-les-patientes\\\/temoignages\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.assip.org\\\/fr\\\/pour-les-patientes\\\/temoignages\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.assip.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pour les patient\u00b7e\u00b7s\",\"item\":\"https:\\\/\\\/www.assip.org\\\/fr\\\/pour-les-patientes\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Qu&#8217;en disent les autres?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.assip.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.assip.org\\\/fr\\\/\",\"name\":\"ASSIP Home Treatment\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.assip.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.assip.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.assip.org\\\/fr\\\/#organization\",\"name\":\"ASSIP Home Treatment\",\"url\":\"https:\\\/\\\/www.assip.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.assip.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.assip.org\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/ASSIP_LOGO_WEB.png\",\"contentUrl\":\"https:\\\/\\\/www.assip.org\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/ASSIP_LOGO_WEB.png\",\"width\":400,\"height\":217,\"caption\":\"ASSIP Home Treatment\"},\"image\":{\"@id\":\"https:\\\/\\\/www.assip.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Qu'en disent les autres? | ASSIP flex","description":"Dans les t\u00e9moignages, vous trouverez les r\u00e9actions des patient(e)s et des th\u00e9rapeutes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.assip.org\/fr\/pour-les-patientes\/temoignages\/","og_locale":"fr_FR","og_type":"article","og_title":"Qu'en disent les autres? | ASSIP flex","og_description":"Dans les t\u00e9moignages, vous trouverez les r\u00e9actions des patient(e)s et des th\u00e9rapeutes.","og_url":"https:\/\/www.assip.org\/fr\/pour-les-patientes\/temoignages\/","og_site_name":"ASSIP flex","article_modified_time":"2026-06-08T11:43:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.assip.org\/fr\/pour-les-patientes\/temoignages\/","url":"https:\/\/www.assip.org\/fr\/pour-les-patientes\/temoignages\/","name":"Qu'en disent les autres? | ASSIP flex","isPartOf":{"@id":"https:\/\/www.assip.org\/fr\/#website"},"datePublished":"2022-09-05T12:04:51+00:00","dateModified":"2026-06-08T11:43:41+00:00","description":"Dans les t\u00e9moignages, vous trouverez les r\u00e9actions des patient(e)s et des th\u00e9rapeutes.","breadcrumb":{"@id":"https:\/\/www.assip.org\/fr\/pour-les-patientes\/temoignages\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.assip.org\/fr\/pour-les-patientes\/temoignages\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.assip.org\/fr\/pour-les-patientes\/temoignages\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.assip.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Pour les patient\u00b7e\u00b7s","item":"https:\/\/www.assip.org\/fr\/pour-les-patientes\/"},{"@type":"ListItem","position":3,"name":"Qu&#8217;en disent les autres?"}]},{"@type":"WebSite","@id":"https:\/\/www.assip.org\/fr\/#website","url":"https:\/\/www.assip.org\/fr\/","name":"ASSIP Home Treatment","description":"","publisher":{"@id":"https:\/\/www.assip.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.assip.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.assip.org\/fr\/#organization","name":"ASSIP Home Treatment","url":"https:\/\/www.assip.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.assip.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.assip.org\/wp-content\/uploads\/2022\/09\/ASSIP_LOGO_WEB.png","contentUrl":"https:\/\/www.assip.org\/wp-content\/uploads\/2022\/09\/ASSIP_LOGO_WEB.png","width":400,"height":217,"caption":"ASSIP Home Treatment"},"image":{"@id":"https:\/\/www.assip.org\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.assip.org\/fr\/wp-json\/wp\/v2\/pages\/3322","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.assip.org\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.assip.org\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.assip.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.assip.org\/fr\/wp-json\/wp\/v2\/comments?post=3322"}],"version-history":[{"count":12,"href":"https:\/\/www.assip.org\/fr\/wp-json\/wp\/v2\/pages\/3322\/revisions"}],"predecessor-version":[{"id":7131,"href":"https:\/\/www.assip.org\/fr\/wp-json\/wp\/v2\/pages\/3322\/revisions\/7131"}],"up":[{"embeddable":true,"href":"https:\/\/www.assip.org\/fr\/wp-json\/wp\/v2\/pages\/3316"}],"wp:attachment":[{"href":"https:\/\/www.assip.org\/fr\/wp-json\/wp\/v2\/media?parent=3322"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}